{"id":680,"date":"2024-11-25T14:26:50","date_gmt":"2024-11-25T14:26:50","guid":{"rendered":"https:\/\/zoimania.com\/?page_id=680"},"modified":"2025-04-29T13:03:43","modified_gmt":"2025-04-29T13:03:43","slug":"pet-design","status":"publish","type":"page","link":"https:\/\/zoimania.com\/en\/pet-design\/","title":{"rendered":"Pet Design"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"680\" class=\"elementor elementor-680\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c16e5a e-flex e-con-boxed e-con e-parent\" data-id=\"7c16e5a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d7660a elementor-widget elementor-widget-heading\" data-id=\"5d7660a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Animali<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4313fe2 e-flex e-con-boxed e-con e-parent\" data-id=\"4313fe2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83dc975 elementor-widget elementor-widget-spacer\" data-id=\"83dc975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8c4d88 eael-product-grid-column-3 elementor-widget elementor-widget-eicon-woocommerce\" data-id=\"b8c4d88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eicon-woocommerce.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-product-grid eael-product-default grid\" id=\"eael-product-grid\" data-widget-id=\"b8c4d88\" data-page-id=\"680\" data-nonce=\"d2a8aa6be6\" >\n            <div class=\"woocommerce\">\n                <p class=\"no-posts-found\">No posts found!<\/p>            <\/div>\n        <\/div>\n\n        <script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                var $scope = jQuery(\".elementor-element-b8c4d88\");\n                var $products = $('.products', $scope);\n                var $layout_mode = $products.data('layout-mode');\n                \n                if ( $layout_mode === 'masonry' ) {\n                    \/\/ init isotope\n                    var $isotope_products = $products.isotope({\n                        itemSelector: \"li.product\",\n                        layoutMode: $layout_mode,\n                        percentPosition: true\n                    });\n\n                    $isotope_products.imagesLoaded().progress( function() {\n                        $isotope_products.isotope('layout');\n                    })\n                    \n                }\n            });\n        <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-906fa95 e-flex e-con-boxed e-con e-parent\" data-id=\"906fa95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Animali Offerta! Appendi Guinzaglio 23,99&nbsp;&euro; Il prezzo originale era: 23,99&nbsp;&euro;.19,99&nbsp;&euro;Il prezzo attuale \u00e8: 19,99&nbsp;&euro;. Scegli l&#039;opzione Questo prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto Porta Ciotole Singola Ciotola 39,99&nbsp;&euro; Aggiungi al carrello Offerta! Porta Ciotole Doppia Ciotola 47,99&nbsp;&euro; Il prezzo originale era: 47,99&nbsp;&euro;.39,99&nbsp;&euro;Il prezzo attuale \u00e8: 39,99&nbsp;&euro;. Scegli l&#039;opzione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-680","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/pages\/680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/comments?post=680"}],"version-history":[{"count":18,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/pages\/680\/revisions"}],"predecessor-version":[{"id":2178,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/pages\/680\/revisions\/2178"}],"wp:attachment":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/media?parent=680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}