{"id":944,"date":"2025-01-14T13:24:42","date_gmt":"2025-01-14T13:24:42","guid":{"rendered":"https:\/\/zoimania.com\/?page_id=944"},"modified":"2025-05-26T14:09:29","modified_gmt":"2025-05-26T14:09:29","slug":"contatti","status":"publish","type":"page","link":"https:\/\/zoimania.com\/en\/contatti\/","title":{"rendered":"Contatti"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"944\" class=\"elementor elementor-944\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d372114 e-flex e-con-boxed e-con e-parent\" data-id=\"d372114\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4cad4c elementor-widget elementor-widget-spacer\" data-id=\"f4cad4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0003471 e-flex e-con-boxed e-con e-parent\" data-id=\"0003471\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b01656 elementor-widget elementor-widget-heading\" data-id=\"4b01656\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hai domande? Contattaci! Siamo qui per aiutarti a creare l\u2019arredamento in acciaio personalizzato perfetto per te.\u200b<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-850a96f eael-wpforms-labels-yes eael-wpforms-form-button-custom elementor-widget elementor-widget-eael-wpforms\" data-id=\"850a96f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"eael-contact-form eael-wpforms eael-custom-radio-checkbox eael-wpforms-align-default\">\n                                <div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-12546\"><form id=\"wpforms-form-12546\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"12546\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/944\" data-token=\"3cb29ed4f0b1e3a69653e4ca9df80042\" data-token-time=\"1788309830\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-12546-field_4-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-trigger wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-12546-field_4\">Condizione <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-12546-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" required=\"required\"><option value=\"Privato\"  class=\"choice-1 depth-1\"  >Privato<\/option><option value=\"Azienda\"  class=\"choice-2 depth-1\"  >Azienda<\/option><\/select><\/div><div id=\"wpforms-12546-field_5-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"5\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-12546-field_5\">Nome e Cognome <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-12546-field_5\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][5]\" aria-errormessage=\"wpforms-12546-field_5-error\" required><\/div>\t\t<div id=\"wpforms-12546-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-12546-field_1\" >tutto aziendale Dicci<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-12546-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-12546-field_7-container\" class=\"wpforms-field wpforms-field-email wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"email\" data-field-id=\"7\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-12546-field_7\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-12546-field_7\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][7]\" spellcheck=\"false\" aria-errormessage=\"wpforms-12546-field_7-error\" required><\/div><div id=\"wpforms-12546-field_9-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"9\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-12546-field_9\">Argomento <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-12546-field_9\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][9]\" required=\"required\"><option value=\"Assistenza su ordini\"  class=\"choice-1 depth-1\"  >Assistenza su ordini<\/option><option value=\"Resi e Rimborsi\"  class=\"choice-2 depth-1\"  >Resi e Rimborsi<\/option><option value=\"Personalizzazione\"  class=\"choice-3 depth-1\"  >Personalizzazione<\/option><option value=\"Collaborazione\"  class=\"choice-4 depth-1\"  >Collaborazione<\/option><option value=\"Candidatura\"  class=\"choice-5 depth-1\"  >Candidatura<\/option><option value=\"Altro\"  class=\"choice-6 depth-1\"  >Altro<\/option><\/select><\/div><div id=\"wpforms-12546-field_10-container\" class=\"wpforms-field wpforms-field-textarea wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"textarea\" data-field-id=\"10\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-12546-field_10\">Dicci tutto<\/label><textarea id=\"wpforms-12546-field_10\" class=\"wpforms-field-medium\" name=\"wpforms[fields][10]\" aria-errormessage=\"wpforms-12546-field_10-error\" ><\/textarea><\/div><div id=\"wpforms-12546-field_12-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"12\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-12546-field_12\">Ragione sociale <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-12546-field_12\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][12]\" aria-errormessage=\"wpforms-12546-field_12-error\" required><\/div><div id=\"wpforms-12546-field_13-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"text\" data-field-id=\"13\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-12546-field_13\">P.IVA <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-12546-field_13\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][13]\" aria-errormessage=\"wpforms-12546-field_13-error\" required><\/div><div id=\"wpforms-12546-field_14-container\" class=\"wpforms-field wpforms-field-email wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"email\" data-field-id=\"14\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-12546-field_14\">Email aziendale <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-12546-field_14\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][14]\" spellcheck=\"false\" aria-errormessage=\"wpforms-12546-field_14-error\" required><\/div><div id=\"wpforms-12546-field_15-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-field wpforms-conditional-show wpforms-conditional-trigger wpforms-field-select-style-classic\" data-field-type=\"select\" data-field-id=\"15\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-12546-field_15\">Argomento <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-12546-field_15\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][15]\" required=\"required\"><option value=\"Fornitura per la tua attivit\u00e0\"  class=\"choice-1 depth-1\"  >Fornitura per la tua attivit\u00e0<\/option><option value=\"Fornitura personalizzata\"  class=\"choice-2 depth-1\"  >Fornitura personalizzata<\/option><option value=\"Consulenza per allestimento\"  class=\"choice-3 depth-1\"  >Consulenza per allestimento<\/option><option value=\"Collaborazione\"  class=\"choice-5 depth-1\"  >Collaborazione<\/option><option value=\"Fiere ed Eventi\"  class=\"choice-6 depth-1\"  >Fiere ed Eventi<\/option><option value=\"Altro\"  class=\"choice-7 depth-1\"  >Altro<\/option><\/select><\/div><div id=\"wpforms-12546-field_16-container\" class=\"wpforms-field wpforms-field-textarea wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"textarea\" data-field-id=\"16\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-12546-field_16\">Dicci tutto<\/label><textarea id=\"wpforms-12546-field_16\" class=\"wpforms-field-medium\" name=\"wpforms[fields][16]\" aria-errormessage=\"wpforms-12546-field_16-error\" ><\/textarea><\/div><div id=\"wpforms-12546-field_18-container\" class=\"wpforms-field wpforms-field-address wpforms-conditional-field wpforms-conditional-show\" data-field-type=\"address\" data-field-id=\"18\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Indirizzo Sede<\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div ><input type=\"text\" id=\"wpforms-12546-field_18\" class=\"wpforms-field-address-address1\" name=\"wpforms[fields][18][address1]\" aria-errormessage=\"wpforms-12546-field_18-error\" ><label for=\"wpforms-12546-field_18\" class=\"wpforms-field-sublabel after\">Address Line 1<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div ><input type=\"text\" id=\"wpforms-12546-field_18-address2\" class=\"wpforms-field-address-address2\" name=\"wpforms[fields][18][address2]\" aria-errormessage=\"wpforms-12546-field_18-address2-error\" ><label for=\"wpforms-12546-field_18-address2\" class=\"wpforms-field-sublabel after\">Address Line 2<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-12546-field_18-city\" class=\"wpforms-field-address-city\" name=\"wpforms[fields][18][city]\" aria-errormessage=\"wpforms-12546-field_18-city-error\" ><label for=\"wpforms-12546-field_18-city\" class=\"wpforms-field-sublabel after\">City<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><select id=\"wpforms-12546-field_18-state\" class=\"wpforms-field-address-state\" name=\"wpforms[fields][18][state]\" aria-errormessage=\"wpforms-12546-field_18-state-error\" ><option class=\"placeholder\" value=\"\" selected disabled>--- Select state ---<\/option><option value=\"AL\" >Alabama<\/option><option value=\"AK\" >Alaska<\/option><option value=\"AZ\" >Arizona<\/option><option value=\"AR\" >Arkansas<\/option><option value=\"CA\" >California<\/option><option value=\"CO\" >Colorado<\/option><option value=\"CT\" >Connecticut<\/option><option value=\"DE\" >Delaware<\/option><option value=\"DC\" >District of Columbia<\/option><option value=\"FL\" >Florida<\/option><option value=\"GA\" >Georgia<\/option><option value=\"HI\" >Hawaii<\/option><option value=\"ID\" >Idaho<\/option><option value=\"IL\" >Illinois<\/option><option value=\"IN\" >Indiana<\/option><option value=\"IA\" >Iowa<\/option><option value=\"KS\" >Kansas<\/option><option value=\"KY\" >Kentucky<\/option><option value=\"LA\" >Louisiana<\/option><option value=\"ME\" >Maine<\/option><option value=\"MD\" >Maryland<\/option><option value=\"MA\" >Massachusetts<\/option><option value=\"MI\" >Michigan<\/option><option value=\"MN\" >Minnesota<\/option><option value=\"MS\" >Mississippi<\/option><option value=\"MO\" >Missouri<\/option><option value=\"MT\" >Montana<\/option><option value=\"NE\" >Nebraska<\/option><option value=\"NV\" >Nevada<\/option><option value=\"NH\" >New Hampshire<\/option><option value=\"NJ\" >New Jersey<\/option><option value=\"NM\" >New Mexico<\/option><option value=\"NY\" >New York<\/option><option value=\"NC\" >North Carolina<\/option><option value=\"ND\" >North Dakota<\/option><option value=\"OH\" >Ohio<\/option><option value=\"OK\" >Oklahoma<\/option><option value=\"OR\" >Oregon<\/option><option value=\"PA\" >Pennsylvania<\/option><option value=\"RI\" >Rhode Island<\/option><option value=\"SC\" >South Carolina<\/option><option value=\"SD\" >South Dakota<\/option><option value=\"TN\" >Tennessee<\/option><option value=\"TX\" >Texas<\/option><option value=\"UT\" >Utah<\/option><option value=\"VT\" >Vermont<\/option><option value=\"VA\" >Virginia<\/option><option value=\"WA\" >Washington<\/option><option value=\"WV\" >West Virginia<\/option><option value=\"WI\" >Wisconsin<\/option><option value=\"WY\" >Wyoming<\/option><\/select><label for=\"wpforms-12546-field_18-state\" class=\"wpforms-field-sublabel after\">State<\/label><\/div><\/div><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"text\" id=\"wpforms-12546-field_18-postal\" class=\"wpforms-field-address-postal wpforms-masked-input\" data-inputmask-mask=\"(99999)|(99999-9999)\" data-inputmask-keepstatic=\"true\" data-rule-inputmask-incomplete=\"1\" name=\"wpforms[fields][18][postal]\" aria-errormessage=\"wpforms-12546-field_18-postal-error\" ><label for=\"wpforms-12546-field_18-postal\" class=\"wpforms-field-sublabel after\">Zip Code<\/label><\/div><\/div><\/fieldset><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-12546-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-12546-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-12546-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"12546\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/pages\/944\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-12546\" class=\"wpforms-submit\" data-alt-text=\"Invio in corso...\" data-submit-text=\"Contattaci\" aria-live=\"assertive\" value=\"wpforms-submit\">Contattaci<\/button><img decoding=\"async\" data-src=\"https:\/\/zoimania.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" class=\"wpforms-submit-spinner lazyload\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><noscript><img decoding=\"async\" src=\"https:\/\/zoimania.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/noscript><\/div><\/form><\/div>  <!-- .wpforms-container -->            <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8532d6e e-flex e-con-boxed e-con e-parent\" data-id=\"8532d6e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb87330 elementor-widget elementor-widget-spacer\" data-id=\"eb87330\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hai domande? Contattaci! Siamo qui per aiutarti a creare l\u2019arredamento in acciaio personalizzato perfetto per te.\u200b Abilita JavaScript nel browser per completare questo modulo.Abilita JavaScript nel browser per completare questo modulo.Condizione *PrivatoAziendaNome e Cognome *Email *Argomento *Assistenza su ordiniResi e RimborsiPersonalizzazioneCollaborazioneCandidaturaAltroDicci tuttoRagione sociale *P.IVA *Email aziendale *Argomento *Fornitura per la tua attivit\u00e0Fornitura personalizzataConsulenza per allestimentoCollaborazioneFiere [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-944","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/pages\/944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/comments?post=944"}],"version-history":[{"count":30,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/pages\/944\/revisions"}],"predecessor-version":[{"id":12566,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/pages\/944\/revisions\/12566"}],"wp:attachment":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/media?parent=944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}