{"id":2761,"date":"2025-04-10T13:46:46","date_gmt":"2025-04-10T13:46:46","guid":{"rendered":"https:\/\/zoimania.com\/?post_type=product&#038;p=2761"},"modified":"2025-05-24T11:19:38","modified_gmt":"2025-05-24T11:19:38","slug":"insegna-luminosa-ce-ste-tremende-stue","status":"publish","type":"product","link":"https:\/\/zoimania.com\/en\/product\/insegna-luminosa-ce-ste-tremende-stue\/","title":{"rendered":"Insegna Luminosa &#8220;Ce Ste Tremende Stue&#8221;"},"content":{"rendered":"<p>Insegna con una espressione dialettale tarantina &#8220;<strong>CE STE TREMIND STUE, VUE A FOTOGRAFIJ?<\/strong>&#8220;, che tradotto vuol dire &#8220;COSA STAI GUARDANDO STUPIDO, VUOI UNA FOTOGRAFIA?, rappresentato in stile Test della vista.<\/p>\n<p>Design d\u2019acciaio.<br \/>\nNon \u00e8 solo un\u2019insegna luminosa: \u00e8 un pezzo d\u2019arredo che illumina con stile e parla per te.<\/p>\n<p>Realizzata in<strong> acciaio verniciato di alta qualit\u00e0<\/strong>, lavorata con taglio laser e retroilluminata da <strong>LED IP67<\/strong>.<\/p>\n<p>Ogni dettaglio \u00e8 curato per offrire un mix perfetto tra estetica e solidit\u00e0.<\/p>\n<p>\u00c8 disponibile in diverse dimensioni e colori, ideale per arredare qualsiasi ambiente: abitazioni, locali, negozi, studi creativi o qualsiasi spazio in cerca di personalit\u00e0.<br \/>\nViene venduto completo di <strong>kit di montaggio<\/strong>, che comprende viti e tasselli da parete.<\/p>\n<p><strong>Dimensioni prodotto:<\/strong><br \/>\nPiccola: 30&#215;20 cm<br \/>\nMedia: 40&#215;27 cm<br \/>\nGrande: 53&#215;35<\/p>\n<p>E se vuoi qualcosa di davvero unico, puoi personalizzarla con colori, testi, disegni o immagini a tua scelta.<\/p>","protected":false},"excerpt":{"rendered":"<p>Insegna con una espressione dialettale tarantina &#8220;<strong>CE STE TREMIND STUE, VUE A FOTOGRAFIJ?<\/strong>&#8220;, che tradotto vuol dire &#8220;COSA STAI GUARDANDO STUPIDO, VUOI UNA FOTOGRAFIA?, rappresentato in stile Test della vista.<\/p>\n<p>Insegna luminosa realizzata in acciaio tagliata a laser e verniciata, con LED interno.<\/p>\n<p>&#8211; Realizzata in acciaio<br \/>\n&#8211; Tagliata a laser<br \/>\n&#8211; LED interno incluso<br \/>\n&#8211; Design personalizzabile<br \/>\n&#8211; Kit montaggio incluso (viti + tasselli)<br \/>\n&#8211; Made in Italy<\/p>","protected":false},"featured_media":11555,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[27],"product_tag":[],"class_list":["post-2761","product","type-product","status-publish","has-post-thumbnail","product_cat-insegne-luminose","pa_colore-arancione","pa_colore-bianco","pa_colore-blu","pa_colore-celeste","pa_colore-giallo","pa_colore-nero","pa_colore-rosa","pa_colore-rosso","pa_colore-verde","pa_colore-viola","pa_dimensione-grande","pa_dimensione-media","pa_dimensione-piccola","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"_links":{"self":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product\/2761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/comments?post=2761"}],"version-history":[{"count":5,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product\/2761\/revisions"}],"predecessor-version":[{"id":11869,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product\/2761\/revisions\/11869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/media\/11555"}],"wp:attachment":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/media?parent=2761"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product_brand?post=2761"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product_cat?post=2761"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product_tag?post=2761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}