{"id":4547,"date":"2025-04-10T23:10:41","date_gmt":"2025-04-10T23:10:41","guid":{"rendered":"https:\/\/zoimania.com\/?post_type=product&#038;p=4547"},"modified":"2025-05-22T09:36:07","modified_gmt":"2025-05-22T09:36:07","slug":"appendi-guinzaglio-dog-mom","status":"publish","type":"product","link":"https:\/\/zoimania.com\/en\/product\/appendi-guinzaglio-dog-mom\/","title":{"rendered":"Appendi Guinzaglio Dog Mom"},"content":{"rendered":"<p>Per il tuo amico a quattro zampe, ecco un accessorio pratico e decorativo che non passa inosservato!<br \/>\nQuesto appendi guinzagli e collari da parete \u00e8 realizzato in acciaio verniciato e mostra con orgoglio il volto del tuo cane, tagliato a laser con precisione e poi verniciato<\/p>\n<p>Puoi scegliere il numero di ganci che preferisci, per appendere guinzagli, collari, pettorine e anche qualche accessorio extra.<br \/>\n\u00c8 disponibile in Diversi colori, ma non solo: possiamo anche personalizzarlo con il nome del tuo fedele compagno, per renderlo davvero unico.<\/p>\n<p>&#8211; In acciaio verniciato: resistente e facile da pulire<br \/>\n&#8211; Volto del cane inciso al laser con dettagli precisi;<br \/>\n&#8211; Fissaggio a parete,<br \/>\n&#8211; Kit di montaggio incluso: viti e tasselli;<br \/>\n&#8211; 100% Made in Italy<\/p>\n<p>Viene venduto completo di kit di montaggio, che comprende viti e tasselli da parete.<br \/>\nN.B.: Il guinzaglio non \u00e8 incluso.<\/p>","protected":false},"excerpt":{"rendered":"<p>Appendi guinzagli e collari  realizzato in acciaio verniciato con il volto del tuo cane, tagliato a laser verniciato<\/p>\n<p>&#8211; In acciaio verniciato: resistente e facile da pulire<br \/>\n&#8211; Volto del cane inciso al laser con dettagli precisi;<br \/>\n&#8211; Fissaggio a parete,<br \/>\n&#8211; Kit di montaggio incluso: viti e tasselli;<br \/>\n&#8211; 100% Made in Italy<\/p>","protected":false},"featured_media":12211,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[37,28],"product_tag":[],"class_list":["post-4547","product","type-product","status-publish","has-post-thumbnail","product_cat-appendi-guinzagli","product_cat-pet-design","pa_colore-arancione","pa_colore-bianco","pa_colore-blu","pa_colore-celeste","pa_colore-giallo","pa_colore-nero","pa_colore-rosa","pa_colore-rosso","pa_colore-verde","pa_colore-viola","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"_links":{"self":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product\/4547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/comments?post=4547"}],"version-history":[{"count":2,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product\/4547\/revisions"}],"predecessor-version":[{"id":12212,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product\/4547\/revisions\/12212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/media\/12211"}],"wp:attachment":[{"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/media?parent=4547"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product_brand?post=4547"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product_cat?post=4547"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zoimania.com\/en\/wp-json\/wp\/v2\/product_tag?post=4547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}